{"id":251292,"date":"2026-07-13T01:09:52","date_gmt":"2026-07-12T22:09:52","guid":{"rendered":"https:\/\/1kitap1.com\/en\/adryel-irmaos-montesi-livro-2-kely-medina-1\/"},"modified":"2026-07-13T01:09:52","modified_gmt":"2026-07-12T22:09:52","slug":"adryel-irmaos-montesi-livro-2-kely-medina-1","status":"publish","type":"post","link":"https:\/\/1kitap1.com\/en\/adryel-irmaos-montesi-livro-2-kely-medina-1\/","title":{"rendered":"Adryel &#8211; Irmaos Montesi Livro 2 &#8211; Kely Medina (1)"},"content":{"rendered":"<figure style=\"text-align:center;margin:0 auto 1.5em;\"><img decoding=\"async\" src=\"https:\/\/1kitap1.com\/en\/wp-content\/uploads\/2026\/07\/9031bb4b5ec6bb00.jpg\" alt=\" - Unknown book cover\" style=\"max-width:300px;width:100%;height:auto;box-shadow:0 4px 12px rgba(0,0,0,.25);border-radius:4px;\"\/><\/figure>\n<p>Em parte, sim; sou esposa de um chefe de m\u00e1fia, e inimigos poderiam me usar contra voc\u00ea. Eu entendo isso. Mas a sua parte obscura n\u00e3o deixa que tudo isso seja verdade, n\u00e3o \u00e9? Voc\u00ea sente necessidade de sentir que \u00e9 meu dono. Um sorriso enigm\u00e1tico dan\u00e7a nos l\u00e1bios dele.<\/p>\n<p>\u2014 E tem raz\u00e3o, ter um homem por a\u00ed querendo roubar minha esposa n\u00e3o \u00e9 motivo suficiente para colocar seguran\u00e7as ao seu redor? \u2014 Sua voz \u00e9 mordaz, uma provoca\u00e7\u00e3o clara. \u2014 N\u00e3o vai me contar sobre as liga\u00e7\u00f5es que voc\u00ea recebe dele? Meus olhos ficam turvos. At\u00e9 o meu celular ele hackeou? Ou ser\u00e1 que deixei tudo t\u00e3o f\u00e1cil, permitindo que ele vasculhasse enquanto eu dormia? \u2014 Voc\u00ea mexeu no meu celular?<\/p>\n<p>Isso \u00e9 uma invas\u00e3o de privacidade! \u2014 Rebato, furiosa. Ele se ajeita na cadeira, procurando algo no bolso, at\u00e9 deslizar o seu celular em cima da mesa na minha dire\u00e7\u00e3o. \u2014 Se isso te fizer sentir menos irritada, pode mexer no meu, mas garanto que n\u00e3o vai encontrar nada que supere a minha decep\u00e7\u00e3o em saber que voc\u00ea ainda mant\u00e9m o n\u00famero dele e recebe suas liga\u00e7\u00f5es \u2014 diz com um tom que curiosamente me estranha por estar sendo calmo.<\/p>\n<p>Ignoro o celular \u00e0 minha frente e o encaro, com compostura \u2014 Eu n\u00e3o atendi nenhuma. \u2014 Me defendo. \u2014 Mas tamb\u00e9m n\u00e3o as rejeitou, nem sequer cogitou me contar. \u2014 Para que eu faria isso? Para que voc\u00ea me trancasse em uma redoma e me impedisse de fazer as minhas aulas? \u2014 Minha voz se eleva sem que eu perceba. Se no restaurante houvesse clientes, estariam olhando para nossa mesa agora.<\/p>\n<p>\u2014 Voc\u00ea acha que sou algum tipo de homem das cavernas? Eu jamais te impediria de fazer o que voc\u00ea gosta! N\u00e3o sou esse tipo de homem! \u2014 Ele desdenha.<\/p>\n<blockquote>\n<p>Diagrama\u00e7\u00e3o: J\u00e9ssica Silva (@js_diagramacaoebanner) Revis\u00e3o: Mariane Tavares (@mariie.books) Leitura cr\u00edtica: Anne Medeiros Ilustra\u00e7\u00f5es: Gabi Nappi 1kitap1.com\/en Todos os direitos reservados, \u00e9 expressamente proibido copiar ou plagiar qualquer parte desta obra sem a devida permiss\u00e3o da autora. Respeite a criatividade e o esfor\u00e7o investidos na cria\u00e7\u00e3o deste conte\u00fado. Redes sociais. Instagram: @kelyautora 1kitap1.com\/en Notas da Autora Gatilhos Fetiches Sinopse Dedicat\u00f3ria Estrelinhas Cap\u00edtulo 01 Cap\u00edtulo 02 Cap\u00edtulo 03 Cap\u00edtulo 04 Cap\u00edtulo 05 Cap\u00edtulo 06 Cap\u00edtulo 07 Cap\u00edtulo 08 Cap\u00edtulo 09 Cap\u00edtulo 10 Cap\u00edtulo 11 Cap\u00edtulo 12 Cap\u00edtulo 13 Cap\u00edtulo 14 Cap\u00edtulo 15 Cap\u00edtulo 16 Cap\u00edtulo 17 Cap\u00edtulo 18 Cap\u00edtulo 19 Cap\u00edtulo 20 Cap\u00edtulo 21 Cap\u00edtulo 22 Cap\u00edtulo 23 Cap\u00edtulo 24 Cap\u00edtulo 25 Cap\u00edtulo 26 Cap\u00edtulo 27 Cap\u00edtulo 28 Cap\u00edtulo 29 Cap\u00edtulo 30 Cap\u00edtulo 31 Cap\u00edtulo 32 Cap\u00edtulo 33 Cap\u00edtulo 34 Cap\u00edtulo 35 Cap\u00edtulo 36 Cap\u00edtulo 37 Cap\u00edtulo 38 Cap\u00edtulo 39 Cap\u00edtulo 40 Cap\u00edtulo 41 Cap\u00edtulo 42 Cap\u00edtulo 43 Cap\u00edtulo 44 Cap\u00edtulo 45 Ep\u00edlogo Agradecimentos 1kitap1.com\/en Ol\u00e1!<\/p>\n<p>Quero te convencer a continuar lendo minhas notas, porque preciso dar alguns avisos importantes. Tudo bem? Primeiro, este livro \u00e9 um dark romance. Embora n\u00e3o seja considerado extremamente pesado, ele aborda temas sens\u00edveis que podem ativar gatilhos. Se voc\u00ea se sentir desconfort\u00e1vel com esse tipo de conte\u00fado, recomendo que pare por aqui. Sua sa\u00fade mental \u00e9 prioridade, e \u00e9 fundamental respeitar seus limites.<\/p>\n<p>Este \u00e9 o segundo livro da trilogia Irm\u00e3os Montesi. Ele pode ser lido de forma independente, sem a necessidade de ler o primeiro volume, mas, se optar por come\u00e7ar do in\u00edcio, voc\u00ea entender\u00e1 melhor como a hist\u00f3ria de Yelena e Adryel come\u00e7ou no livro Ares; um vicio de amor e obsess\u00e3o.<\/p>\n<p>Nesta obra, \u00e9 contada a hist\u00f3ria de duas pessoas completamente arruinadas, quebradas e desajustadas, que tentam, de forma torta, se encaixar uma na outra. Suas atitudes s\u00e3o controversas, seu amor \u00e9 possessivo e doentio, mas \u00e9 importante destacar que isso n\u00e3o significa que eu, como autora, apoio ou romantizo essas a\u00e7\u00f5es. Por favor, leia com a mente aberta, sabendo que, apesar das atitudes e escolhas dos protagonistas, esta \u00e9 apenas uma obra de fic\u00e7\u00e3o.<\/p>\n<p>Yelena \u00e9 uma mulher forjada pelo \u00f3dio, manipulada pelo pr\u00f3prio pai, e punida por ambi\u00e7\u00f5es que nunca foram dela.<\/p>\n<\/blockquote>\n<p><em>This is a short excerpt from the opening of &ldquo;&rdquo; by Unknown, quoted for review and introduction purposes. All rights belong to the copyright holders.<\/em><\/p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Table of Contents<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/1kitap1.com\/en\/adryel-irmaos-montesi-livro-2-kely-medina-1\/#Book_Information\" >Book Information<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/1kitap1.com\/en\/adryel-irmaos-montesi-livro-2-kely-medina-1\/#Reading_Word_Statistics\" >Reading &amp; Word Statistics<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/1kitap1.com\/en\/adryel-irmaos-montesi-livro-2-kely-medina-1\/#Most_Frequent_Words\" >Most Frequent Words<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/1kitap1.com\/en\/adryel-irmaos-montesi-livro-2-kely-medina-1\/#PDF_Download\" >PDF Download<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"Book_Information\"><\/span>Book Information<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<ul>\n<li><strong>Unique ID:<\/strong> 9031bb4b5ec6bb00<\/li>\n<li><strong>File Extension:<\/strong> .pdf<\/li>\n<li><strong>File Size:<\/strong> 4,056,983 bytes (3.869 MB)<\/li>\n<li><strong>Title:<\/strong> &#8211;<\/li>\n<li><strong>Author:<\/strong> Unknown<\/li>\n<li><strong>Pages:<\/strong> 511<\/li>\n<li><strong>Language:<\/strong> Portuguese (pt)<\/li>\n<\/ul>\n<h2><span class=\"ez-toc-section\" id=\"Reading_Word_Statistics\"><\/span>Reading &amp; Word Statistics<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<ul>\n<li><strong>Estimated Reading Time:<\/strong> 698.93 minutes<\/li>\n<li><strong>Total Words:<\/strong> 139,787<\/li>\n<li><strong>Total Characters:<\/strong> 791,452<\/li>\n<li><strong>Average Words per Page:<\/strong> 273.56<\/li>\n<li><strong>Average Characters per Page:<\/strong> 1548.83<\/li>\n<\/ul>\n<h2><span class=\"ez-toc-section\" id=\"Most_Frequent_Words\"><\/span>Most Frequent Words<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>n\u00e3o (2494), com (1876), ele (1768), meu (1575), uma (1418), minha (1378), voc\u00ea (1269), mas (1175), sua (922), ela (774), seu (731), isso (693), mim (665), meus (583), olhos (564), seus (544), sem (400), yelena (400), tudo (396), algo (384), ainda (357), corpo (352), voz (352), pai (350), minhas (313), dele (311), enquanto (304), mesmo (286), olhar (276), at\u00e9 (271), m\u00e3os (270), suas (267), cada (262), estou (261), homem (257), pelo (243), cabe\u00e7a (242), apenas (236), sorriso (234), foi (227), sinto (225), antes (225), palavras (225), rosto (224), m\u00e3o (223), tentando (222), agora (221), t\u00e3o (220), dedos (220), nunca (214), assim (211), vai (211), sei (209), ter (205), adryel (204), posso (202), pela (200), dos (199), lado (198), nada (198), dentro (197), fazer (197), faz (196), l\u00e1bios (193), estava (191), contra (181), essa (178), qualquer (176), fosse (176), quero (173), forma (172), tempo (167), pode (165), queria (164), bem (158), tem (157), vou (154), ent\u00e3o (152), esse (151), marido (149), entre (148), sempre (147), parece (146), cora\u00e7\u00e3o (144), momento (141), tom (140), consigo (138), poderia (138), dela (134), n\u00f3s (134), tamb\u00e9m (131), preciso (130), seria (129), sou (129), vez (127), m\u00e3e (127), quer (127), peito (127), for\u00e7a (126), talvez (126).<\/p>\n<h2><span class=\"ez-toc-section\" id=\"PDF_Download\"><\/span>PDF Download<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p style=\"text-align:center;\"><a href=\"https:\/\/1kitap1.com\/en\/wp-content\/uploads\/2026\/07\/adryel-irmaos-montesi-livro-2-kely-medina-1.pdf\" download rel=\"nofollow\" style=\"display:inline-block;background:#2271b1;color:#ffffff;padding:14px 36px;border-radius:6px;text-decoration:none;font-weight:bold;font-size:1.05em;\">&#11015;&#65039; PDF Download<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Em parte, sim; sou esposa de um chefe de m\u00e1fia, e inimigos poderiam me usar contra voc\u00ea. Eu entendo isso. Mas a sua parte obscura n\u00e3o deixa que tudo isso seja verdade, n\u00e3o \u00e9? Voc\u00ea sente necessidade de sentir que \u00e9 meu dono. Um sorriso enigm\u00e1tico dan\u00e7a nos l\u00e1bios dele. \u2014 E tem raz\u00e3o, ter [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":251290,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[34851],"tags":[],"class_list":["post-251292","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-portuguese"],"blocksy_meta":[],"_links":{"self":[{"href":"https:\/\/1kitap1.com\/en\/wp-json\/wp\/v2\/posts\/251292","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/1kitap1.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/1kitap1.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/1kitap1.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/1kitap1.com\/en\/wp-json\/wp\/v2\/comments?post=251292"}],"version-history":[{"count":0,"href":"https:\/\/1kitap1.com\/en\/wp-json\/wp\/v2\/posts\/251292\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/1kitap1.com\/en\/wp-json\/wp\/v2\/media\/251290"}],"wp:attachment":[{"href":"https:\/\/1kitap1.com\/en\/wp-json\/wp\/v2\/media?parent=251292"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/1kitap1.com\/en\/wp-json\/wp\/v2\/categories?post=251292"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/1kitap1.com\/en\/wp-json\/wp\/v2\/tags?post=251292"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}