{"id":264720,"date":"2026-07-15T02:23:03","date_gmt":"2026-07-14T23:23:03","guid":{"rendered":"https:\/\/1kitap1.com\/en\/i-made-a-deal-with-the-devil-kazzen\/"},"modified":"2026-07-15T02:23:03","modified_gmt":"2026-07-14T23:23:03","slug":"i-made-a-deal-with-the-devil-kazzen","status":"publish","type":"post","link":"https:\/\/1kitap1.com\/en\/i-made-a-deal-with-the-devil-kazzen\/","title":{"rendered":"I Made A Deal With The Devil &#8211; Kazzen"},"content":{"rendered":"<figure style=\"text-align:center;margin:0 auto 1.5em;\"><img decoding=\"async\" src=\"https:\/\/1kitap1.com\/en\/wp-content\/uploads\/2026\/07\/fb3c953d10124e75.jpg\" alt=\" - Unknown book cover\" style=\"max-width:300px;width:100%;height:auto;box-shadow:0 4px 12px rgba(0,0,0,.25);border-radius:4px;\"\/><\/figure>\n<p>&#8220;Seu corpo n\u00e3o est\u00e1 apenas me acolhendo &#8211; est\u00e1 morrendo de vontade de me ver. N\u00f3s nos encaixamos t\u00e3o perfeitamente porque voc\u00ea foi feita para mim, Eva. Voc\u00ea entende a verdade agora?&#8221; Eva ficou sem palavras naquele momento. Sentia-se t\u00e3o plena, e &#8211; Deus! &#8211; n\u00e3o conseguia encontrar a palavra certa para descrever, mas a sensa\u00e7\u00e3o dele era t\u00e3o avassaladora que beirava o surreal.<\/p>\n<p>A d\u00favida persistente sobre se ele havia mudado desde a \u00faltima vez que dormiram juntos, ou se era simplesmente o tempo que havia passado desde a \u00faltima vez que o sentira, rondava sua mente, sem resposta. &#8220;Eva,&#8221; seu rosnado ecoou pelo ar denso, atraindo a aten\u00e7\u00e3o dela para seu corpo tenso. Sob ela, seus m\u00fasculos estavam contra\u00eddos como molas comprimidas, sua pele estava \u00famida de suor e seu olhar estava repleto de um prazer puro e intenso.<\/p>\n<p>\u201cT\u00e3o divinamente requintada como sempre, minha querida&#8230;\u201d sua respira\u00e7\u00e3o falhou enquanto ele lambia a gota de saliva que escorria pelo canto da boca. E ent\u00e3o, libertou o seio dela e o levou \u00e0 boca, enquanto a apertava contra si como se desejasse fundir seus corpos em uma \u00fanica entidade indissol\u00favel. Aconchegada t\u00e3o perto, Eva era tomada pelas sensa\u00e7\u00f5es, mesmo sem se mover. Era demais, mas ela se agarrou a ele, entrela\u00e7ando a m\u00e3o em volta da cabe\u00e7a dele e passando os dedos pelos fios de cabelo, que lhe eram desconhecidos.<\/p>\n<p>Enquanto seu corpo respondia aos seus toques, um rosnado selvagem escapou dele. Seus bra\u00e7os relaxaram ligeiramente, e no instante em que Eva sentiu a m\u00e3o dele se mover em dire\u00e7\u00e3o \u00e0s suas n\u00e1degas &#8211; provavelmente para ergu\u00ea-la &#8211; seu cora\u00e7\u00e3o disparou em antecipa\u00e7\u00e3o ao que estava por vir. Contudo, antes que ele pudesse agir, o corpo de Eva se retesou ao som de algo atingindo o carro. Seu cora\u00e7\u00e3o disparou quando seus olhos se voltaram para a janela, onde as sombras de pessoas se aproximavam perigosamente.<\/p>\n<p>O sussurro dele foi um fio de calma em meio ao p\u00e2nico dela. &#8220;Relaxe, Eva. Lembre-se, ningu\u00e9m mais pode te ver assim.&#8221; A confian\u00e7a de Eva na promessa dele era absoluta, e sua fera interior a impelia a se entregar ao abandono imprudente e abra\u00e7ar a emo\u00e7\u00e3o daquele momento. Mas, mesmo que n\u00e3o pudessem ver, a ideia de o carro trair seus planos com seus movimentos atormentava sua mente ansiosa.<\/p>\n<p>Ela balan\u00e7ou a cabe\u00e7a freneticamente. &#8220;Eu n\u00e3o consigo&#8230; por favor&#8230; vamos fazer isso em casa.&#8221; Qualquer que fosse a emo\u00e7\u00e3o que transparecesse em seu rosto naquele instante, ela o afetou imediatamente. A lux\u00faria ardente em seus olhos suavizou-se.<\/p>\n<blockquote>\n<p>Uma jovem vestida com um traje de neg\u00f3cios impec\u00e1vel e formal entrou repentinamente pela porta. Todos os presentes na sala voltaram seus olhares para a mulher, que caminhava com passos confiantes. Era Evangeline Young. Ela usava \u00f3culos de arma\u00e7\u00e3o grossa e redonda, apoiados na ponte do nariz, e o cabelo estava preso em um coque firme e elegante. Sua apar\u00eancia geral era a de uma mulher de neg\u00f3cios rigorosa e objetiva.<\/p>\n<p>E ela era exatamente isso. &#8220;Evangeline, o que voc\u00ea est\u00e1 fazendo aqui?&#8221; perguntou Samuel Young, levantando-se da cabeceira de uma longa mesa. Ele estava em meio a uma reuni\u00e3o com o conselho administrativo em seu elegante escrit\u00f3rio. &#8220;O que o senhor quer dizer com isso, vov\u00f4? Eu sou a CEO desta empresa, e o senhor est\u00e1 me perguntando o que estou fazendo aqui?&#8221;, disparou Evangeline. &#8220;Eva, saia daqui. Falarei com voc\u00ea quando chegarmos em casa.&#8221; O velho acenou com a m\u00e3o em um gesto de desd\u00e9m enquanto se recostava na cadeira.<\/p>\n<p>Os olhos de Eva se arregalaram enquanto ela permanecia ali, teimosamente, e respondeu: &#8220;Vov\u00f4, estou completamente confusa. Exijo uma explica\u00e7\u00e3o aqui e agora sobre por que o senhor est\u00e1 fazendo isso.&#8221; Ela cerrou os punhos. &#8220;Evangeline!&#8221; gritou Samuel para ela. &#8220;A partir de hoje, voc\u00ea deixar\u00e1 o cargo de CEO desta empresa. O conselho administrativo j\u00e1 escolheu quem a substituir\u00e1, e ela assumir\u00e1 o cargo o mais breve poss\u00edvel.&#8221;<\/p>\n<p>Eva ficou sem palavras, at\u00f4nita. Seu av\u00f4 acabara de gritar com ela e demiti- la do cargo de CEO? Bem na frente de todas aquelas pessoas? Seu corpo permaneceu im\u00f3vel enquanto ela observava os rostos de todos ao redor da mesa. Nenhum deles demonstrava qualquer sinal de choque, como ela estava sentindo naquele momento.<\/p>\n<p>Eles s\u00f3 conseguiam desviar o olhar quando seus olhos encontravam os deles. Aparentemente, ela era a \u00faltima a saber&#8230; &#8220;O que voc\u00ea disse? Est\u00e1 me destituindo do meu cargo? Por qu\u00ea?&#8221; Eva perguntou incr\u00e9dula enquanto caminhava lentamente at\u00e9 onde seu av\u00f4 estava sentado. &#8220;Isso n\u00e3o faz sentido nenhum. Estou sonhando? Eu sou a CEO da Corpora\u00e7\u00e3o XY.<\/p>\n<p>Eu sou a respons\u00e1vel por levar esta empresa ao patamar atual. Por que estou sendo rebaixada do nada?&#8221; &#8220;Eva, v\u00e1 para casa. Eu falo com voc\u00ea depois&#8221;, respondeu Samuel com um suspiro, sem responder \u00e0s perguntas dela. &#8220;N\u00e3o!&#8221; Eva explodiu de raiva, cerrando os dedos com tanta for\u00e7a que cravavam nas palmas das m\u00e3os. &#8220;Exijo uma explica\u00e7\u00e3o agora mesmo, vov\u00f4! Diga-me&#8230; o que diabos est\u00e1 acontecendo? Diga-me -&#8221; &#8220;Porque voc\u00ea n\u00e3o \u00e9 minha neta leg\u00edtima!! \u00c9 por isso!&#8221;<\/p>\n<p>A voz de Samuel trovejou sobre o caos enquanto ele se levantava novamente. Eva ficou paralisada de choque. &#8220;O qu\u00ea?&#8221;, pensou. &#8220;Eu n\u00e3o sou um membro leg\u00edtimo da fam\u00edlia Young?<\/p>\n<\/blockquote>\n<p><em>This is a short excerpt from the opening of &ldquo;&rdquo; by Unknown, quoted for review and introduction purposes. All rights belong to the copyright holders.<\/em><\/p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_85 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Table of Contents<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/1kitap1.com\/en\/i-made-a-deal-with-the-devil-kazzen\/#Book_Information\" >Book Information<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/1kitap1.com\/en\/i-made-a-deal-with-the-devil-kazzen\/#Reading_Word_Statistics\" >Reading &amp; Word Statistics<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/1kitap1.com\/en\/i-made-a-deal-with-the-devil-kazzen\/#Most_Frequent_Words\" >Most Frequent Words<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/1kitap1.com\/en\/i-made-a-deal-with-the-devil-kazzen\/#PDF_Download\" >PDF Download<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"Book_Information\"><\/span>Book Information<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<ul>\n<li><strong>Unique ID:<\/strong> fb3c953d10124e75<\/li>\n<li><strong>File Extension:<\/strong> .pdf<\/li>\n<li><strong>File Size:<\/strong> 7,139,122 bytes (6.808 MB)<\/li>\n<li><strong>Title:<\/strong> &#8211;<\/li>\n<li><strong>Author:<\/strong> Unknown<\/li>\n<li><strong>Pages:<\/strong> 1844<\/li>\n<li><strong>Language:<\/strong> Portuguese (pt)<\/li>\n<\/ul>\n<h2><span class=\"ez-toc-section\" id=\"Reading_Word_Statistics\"><\/span>Reading &amp; Word Statistics<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<ul>\n<li><strong>Estimated Reading Time:<\/strong> 2034.99 minutes<\/li>\n<li><strong>Total Words:<\/strong> 406,998<\/li>\n<li><strong>Total Characters:<\/strong> 2,425,777<\/li>\n<li><strong>Average Words per Page:<\/strong> 220.71<\/li>\n<li><strong>Average Characters per Page:<\/strong> 1315.5<\/li>\n<\/ul>\n<h2><span class=\"ez-toc-section\" id=\"Most_Frequent_Words\"><\/span>Most Frequent Words<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>ela (8174), ele (7687), n\u00e3o (6109), com (5648), voc\u00ea (3780), eva (3759), sua (3480), uma (3463), seu (3240), gage (3061), mas (2803), seus (2572), estava (2279), dela (1969), olhos (1770), dele (1687), enquanto (1650), isso (1493), ent\u00e3o (1408), agora (1225), ainda (1201), t\u00e3o (1146), olhar (1108), voz (1101), mesmo (1096), antes (1094), havia (1000), tudo (985), assim (932), at\u00e9 (931), disse (922), suas (897), vez (892), sem (871), m\u00e3o (825), bem (825), foi (815), rosto (813), sorriso (779), l\u00e1bios (764), algo (748), tempo (713), cabe\u00e7a (712), calyx (644), muito (641), tinha (633), novamente (603), finalmente (602), nunca (588), apenas (580), homem (571), corpo (566), fazer (566), pouco (563), lhe (560), fez (560), cap\u00edtulo (555), momento (551), meu (548), parecia (547), eles (539), oceanofpdf (537), minha (529), nada (522), aquele (502), palavras (499), sabia (497), conseguia (495), dos (482), queria (472), instante (466), tamb\u00e9m (465), ter (462), contra (447), sempre (445), estou (442), pelo (439), cada (436), realmente (430), nem (425), dizer (419), querida (413), m\u00e3os (409), respondeu (407), depois (407), tivesse (398), ficou (397), fosse (393), sim (392), quase (389), simplesmente (388), estivesse (384), porta (379), ver (376), cora\u00e7\u00e3o (376), noite (376), naquele (375), essa (375), sil\u00eancio (374), perguntou (373).<\/p>\n<h2><span class=\"ez-toc-section\" id=\"PDF_Download\"><\/span>PDF Download<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p style=\"text-align:center;\"><a href=\"https:\/\/1kitap1.com\/en\/wp-content\/uploads\/2026\/07\/i-made-a-deal-with-the-devil-kazzen.pdf\" download rel=\"nofollow\" style=\"display:inline-block;background:#2271b1;color:#ffffff;padding:14px 36px;border-radius:6px;text-decoration:none;font-weight:bold;font-size:1.05em;\">&#11015;&#65039; PDF Download<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Seu corpo n\u00e3o est\u00e1 apenas me acolhendo &#8211; est\u00e1 morrendo de vontade de me ver. N\u00f3s nos encaixamos t\u00e3o perfeitamente porque voc\u00ea foi feita para mim, Eva. Voc\u00ea entende a verdade agora?&#8221; Eva ficou sem palavras naquele momento. Sentia-se t\u00e3o plena, e &#8211; Deus! &#8211; n\u00e3o conseguia encontrar a palavra certa para descrever, mas a [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":264718,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[34851],"tags":[],"class_list":["post-264720","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-portuguese"],"blocksy_meta":[],"_links":{"self":[{"href":"https:\/\/1kitap1.com\/en\/wp-json\/wp\/v2\/posts\/264720","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/1kitap1.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/1kitap1.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/1kitap1.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/1kitap1.com\/en\/wp-json\/wp\/v2\/comments?post=264720"}],"version-history":[{"count":0,"href":"https:\/\/1kitap1.com\/en\/wp-json\/wp\/v2\/posts\/264720\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/1kitap1.com\/en\/wp-json\/wp\/v2\/media\/264718"}],"wp:attachment":[{"href":"https:\/\/1kitap1.com\/en\/wp-json\/wp\/v2\/media?parent=264720"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/1kitap1.com\/en\/wp-json\/wp\/v2\/categories?post=264720"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/1kitap1.com\/en\/wp-json\/wp\/v2\/tags?post=264720"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}